
{"id":32454,"date":"2026-06-22T09:16:30","date_gmt":"2026-06-22T02:16:30","guid":{"rendered":"https:\/\/www.kmutt.ac.th\/procurement\/?post_type=kmutt_procurement&#038;p=32454"},"modified":"2026-06-23T09:22:49","modified_gmt":"2026-06-23T02:22:49","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9b%e0%b8%b1%e0%b8%95%e0%b8%a2%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b9%81-75","status":"publish","type":"kmutt_procurement","link":"https:\/\/www.kmutt.ac.th\/procurement\/kmutt_procurement\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9b%e0%b8%b1%e0%b8%95%e0%b8%a2%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b9%81-75\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a"},"content":{"rendered":"\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e0a\u0e38\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e2a\u0e15\u0e17\u0e31\u0e28\u0e19\u0e39\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 Hybrid Meeting Room (\u0e2b\u0e49\u0e2d\u0e07 222)<\/p>\n\n\n\n<p>\u0e04\u0e13\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14<\/p>\n\n\n\n<p><\/p>\n","protected":false},"author":198,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_themeisle_gutenberg_block_has_review":false},"categories":[139],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement\/32454"}],"collection":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement"}],"about":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/types\/kmutt_procurement"}],"author":[{"embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/users\/198"}],"wp:attachment":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/media?parent=32454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/categories?post=32454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}