
{"id":26532,"date":"2024-12-02T16:10:32","date_gmt":"2024-12-02T09:10:32","guid":{"rendered":"https:\/\/www.kmutt.ac.th\/procurement\/?post_type=kmutt_procurement&#038;p=26532"},"modified":"2024-12-02T16:10:33","modified_gmt":"2024-12-02T09:10:33","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9e%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%b4%e0%b9%88%e0%b8%87%e0%b9%81%e0%b8%a7%e0%b8%94%e0%b8%a5%e0%b9%89%e0%b8%ad%e0%b8%a1-72","status":"publish","type":"kmutt_procurement","link":"https:\/\/www.kmutt.ac.th\/procurement\/kmutt_procurement\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9e%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%aa%e0%b8%b4%e0%b9%88%e0%b8%87%e0%b9%81%e0%b8%a7%e0%b8%94%e0%b8%a5%e0%b9%89%e0%b8%ad%e0%b8%a1-72\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38"},"content":{"rendered":"\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e27\u0e35-\u0e27\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e1a\u0e34\u0e25-\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c\u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e40\u0e23\u0e14 \u0e2a\u0e40\u0e1b\u0e01\u0e42\u0e15\u0e23\u0e42\u0e1f\u0e42\u0e15\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/p>\n\n\n\n<p>(UV-VIS-NIR Spectrophotometer) \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/p>\n","protected":false},"author":52,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_themeisle_gutenberg_block_has_review":false},"categories":[136,140],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement\/26532"}],"collection":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement"}],"about":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/types\/kmutt_procurement"}],"author":[{"embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/users\/52"}],"wp:attachment":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/media?parent=26532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/categories?post=26532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}