
{"id":14063,"date":"2021-12-21T16:50:29","date_gmt":"2021-12-21T09:50:29","guid":{"rendered":"https:\/\/www.kmutt.ac.th\/procurement2\/?post_type=kmutt_procurement&#038;p=14063"},"modified":"2021-12-21T16:50:30","modified_gmt":"2021-12-21T09:50:30","slug":"%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%aa%e0%b8%ab%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3-2","status":"publish","type":"kmutt_procurement","link":"https:\/\/www.kmutt.ac.th\/procurement\/kmutt_procurement\/%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%aa%e0%b8%ab%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%81%e0%b8%b2%e0%b8%a3-2\/","title":{"rendered":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e2b\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23"},"content":{"rendered":"\n<p>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e23\u0e32\u0e04\u0e32\u0e01\u0e25\u0e32\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2565 \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<\/p>\n","protected":false},"author":5,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_themeisle_gutenberg_block_has_review":false},"categories":[564,136],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement\/14063"}],"collection":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/kmutt_procurement"}],"about":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/types\/kmutt_procurement"}],"author":[{"embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/users\/5"}],"wp:attachment":[{"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/media?parent=14063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kmutt.ac.th\/procurement\/wp-json\/wp\/v2\/categories?post=14063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}